{"id":307728,"date":"2017-01-17T10:46:00","date_gmt":"2017-01-17T09:46:00","guid":{"rendered":"https:\/\/alicanteturismo.com\/licitaciones\/projecte-de-reforc-estructural-parcial-sector-n-e-del-parquing-de-la-placa-del-port-moll-de-llevant-alacant\/"},"modified":"2025-05-20T12:03:50","modified_gmt":"2025-05-20T10:03:50","slug":"projecte-de-reforc-estructural-parcial-sector-n-e-del-parquing-de-la-placa-del-port-moll-de-llevant-alacant","status":"publish","type":"licitaciones","link":"https:\/\/dev.alicanteturismo.com\/ca\/licitaciones\/projecte-de-reforc-estructural-parcial-sector-n-e-del-parquing-de-la-placa-del-port-moll-de-llevant-alacant\/","title":{"rendered":"Projecte de refor\u00e7 estructural parcial. Sector N-E del P\u00e0rquing de la Pla\u00e7a del Port. Moll de Llevant. Alacant."},"content":{"rendered":"<h3><strong>Consulta d&#8217;expedients de contractaci\u00f3<\/strong><\/h3>\n<p><\/p>\n<ul>\n<li><strong>Codi d&#8217;expedient<\/strong>: 00001-17-*PMT-0001<\/li>\n<li><strong>Objecte<\/strong>: Projecte de refor\u00e7 estructural parcial. Sector N-E del P\u00e0rquing de la Pla\u00e7a del Port. Moll de Llevant. Alacant.<\/li>\n<li><strong>Tipus de contracte<\/strong>: Obres.<\/li>\n<li><strong>Procediment d&#8217;adjudicaci\u00f3<\/strong>: Negociat sense publicitat.<\/li>\n<li><strong>Tipus de licitaci\u00f3<\/strong>: 81.000 \u20ac euros, IVA no incl\u00f2s<\/li>\n<li><strong>Depend\u00e8ncia de tramitaci\u00f3<\/strong>: Patronat Municipal de Turisme i Platges.<\/li>\n<li><strong>\u00d2rgan de contractaci\u00f3<\/strong>: PRESIDENTA *PMT.<\/li>\n<li><strong>Data de formalitzaci\u00f3 del contracte<\/strong>: 17\/01\/2017<\/li>\n<\/ul>\n<p><\/p>\n<h3><strong>Documents Associats<\/strong><\/h3>\n<p><\/p>\n<table summary=\"Documentos\" width=\"100%\">\n<colgroup>\n<col width=\"29%\" \/>\n<col width=\"21%\" \/>\n<col width=\"21%\" \/>\n<col width=\"29%\" \/><\/colgroup>\n<tbody>\n<tr class=\"par\">\n<th><span style=\"font-weight: 400;\">Documente <\/span><\/th>\n<th class=\"centro\" abbr=\"Fecha\"><span style=\"font-weight: 400;\">Data Publicaci\u00f3<\/span><\/th>\n<th class=\"centro\" abbr=\"Firma y sello de tiempo\"><span style=\"font-weight: 400;\">Verificaci\u00f3 Firma<\/span><\/th>\n<th><span style=\"font-weight: 400;\">Observacions<\/span><\/th>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=1&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=1&amp;orden=4\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Anunci de formalitzaci\u00f3 de contracte<\/span><\/a><\/td>\n<td class=\"centro\">25\/01\/2017 11:37 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Anunci de formalitzaci\u00f3<\/p>\n<div><span style=\"color: #ff0000;\">AVISE<\/span><\/div>\n<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><span style=\"color: #ff0000;\"><a class=\"pdf\" style=\"color: #ff0000;\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=1&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=1&amp;orden=3\" rel=\"external noopener\" target=\"_blank\">Adjudicaci\u00f3\u00a0<\/a><\/span><\/td>\n<td class=\"centro\"><span style=\"color: #ff0000;\">17\/01\/2017 14:22 h.<\/span><\/td>\n<td class=\"centro\"><span style=\"color: #ff0000;\">&#8211;<\/span><\/td>\n<td class=\"izquierda\"><span style=\"color: #ff0000;\">Decret d&#8217;adjudicaci\u00f3<\/span><\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=1&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=1&amp;orden=2\" rel=\"external noopener\" target=\"_blank\">Altres<\/a><\/td>\n<td class=\"centro\">03\/01\/2017 12:36 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Informe de valoraci\u00f3<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=1&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=1&amp;orden=1\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Classificaci\u00f3 dels licitadors<\/span><\/a><\/td>\n<td class=\"centro\">03\/01\/2017 10:05 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Decret de classificaci\u00f3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n<p><\/p>\n","protected":false},"featured_media":295940,"parent":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-307728","licitaciones","type-licitaciones","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/licitaciones\/307728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/licitaciones"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/types\/licitaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media\/295940"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media?parent=307728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}