{"id":307749,"date":"2017-06-14T11:36:00","date_gmt":"2017-06-14T09:36:00","guid":{"rendered":"https:\/\/alicanteturismo.com\/licitaciones\/la-prestacio-del-servici-de-manteniment-i-explotacio-de-larea-de-pernocta-en-transit-per-a-autocaravanes-dalacant\/"},"modified":"2017-06-14T11:36:00","modified_gmt":"2017-06-14T09:36:00","slug":"la-prestacio-del-servici-de-manteniment-i-explotacio-de-larea-de-pernocta-en-transit-per-a-autocaravanes-dalacant","status":"publish","type":"licitaciones","link":"https:\/\/dev.alicanteturismo.com\/ca\/licitaciones\/la-prestacio-del-servici-de-manteniment-i-explotacio-de-larea-de-pernocta-en-transit-per-a-autocaravanes-dalacant\/","title":{"rendered":"La prestaci\u00f3 del servici de manteniment i explotaci\u00f3 de l&#8217;\u00e0rea de pernocta en tr\u00e0nsit per a autocaravanes d&#8217;Alacant"},"content":{"rendered":"<h2><strong>Consulta d&#8217;expedients de contractaci\u00f3<\/strong><\/h2>\n<ul>\n<li>Codi d&#8217;expedient: 00027-17-*PMT-0007<\/li>\n<li>Objecte: La prestaci\u00f3 del servici de manteniment i explotaci\u00f3 de l&#8217;\u00e0rea de pernocta en tr\u00e0nsit per a autocaravanes d&#8217;Alacant<\/li>\n<li>Tipus de contracte: Especials.<\/li>\n<li>Procediment d&#8217;adjudicaci\u00f3: Negociat sense publicitat.<\/li>\n<li>Valor estimat: 48.000,00 euros.<\/li>\n<li>Tipus de licitaci\u00f3: 24.000,00 \u20ac euros (per a m\u00e9s informaci\u00f3 veure anunci)<\/li>\n<li>Depend\u00e8ncia de tramitaci\u00f3: Patronat Municipal de Turisme i Platges.<\/li>\n<li>\u00d2rgan de contractaci\u00f3: Presidenta del Patronat de Turisme i Platges d&#8217;Alacant.<\/li>\n<li>Lloc de presentaci\u00f3 de proposicions o sol\u00b7licituds de participaci\u00f3: Patronat Municipal de Turisme i Platges<br \/>\nAdre\u00e7a: C\/ Cervantes, n\u00fam. 3 &#8211; Entresol C.P: 03002 &#8211; ALACANT<br \/>\nVeure mapa<\/li>\n<li>Data l\u00edmit de presentaci\u00f3: 21\/06\/2017 a les 14.00 hores.<\/li>\n<li>Data de formalitzaci\u00f3 del contracte: 09\/08\/2017<\/li>\n<\/ul>\n<h3><strong>Documents Associats<\/strong><\/h3>\n<table summary=\"Documentos\" width=\"100%\">\n<colgroup>\n<col width=\"29%\" \/>\n<col width=\"21%\" \/>\n<col width=\"21%\" \/>\n<col width=\"29%\" \/><\/colgroup>\n<tbody>\n<tr class=\"par\">\n<th><span style=\"font-weight: 400;\">Documente <\/span><\/th>\n<th class=\"centro\" abbr=\"Fecha\"><span style=\"font-weight: 400;\">Data Publicaci\u00f3 <\/span><\/th>\n<th class=\"centro\" abbr=\"Firma y sello de tiempo\"><span style=\"font-weight: 400;\">Verificaci\u00f3 Firma <\/span><\/th>\n<th><span style=\"font-weight: 400;\">Observacions<\/span><\/th>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=9\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Anunci de formalitzaci\u00f3 de contracte<\/span><\/a><\/td>\n<td class=\"centro\">11\/08\/2017 12:48 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Anunci de formalitzaci\u00f3 del contracte<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=8\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Adjudicaci\u00f3<\/span><\/a><\/td>\n<td class=\"centro\">09\/08\/2017 10:20 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">decret d&#8217;adjudicaci\u00f3<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=7\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Classificaci\u00f3 dels licitadors<\/span><\/a><\/td>\n<td class=\"centro\">29\/06\/2017 11:00 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Decret de classificaci\u00f3<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=6\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Altres<\/span><\/a><\/td>\n<td class=\"centro\">15\/06\/2017 11:47 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Modificaci\u00f3 horari per a presentaci\u00f3 oferixes<\/p>\n<p>AVISE<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=5\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Altres<\/span><\/a><\/td>\n<td class=\"centro\">14\/06\/2017 12:12 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Mitjans per a acreditar la solv\u00e8ncia<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=4\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Altres<\/span><\/a><\/td>\n<td class=\"centro\">14\/06\/2017 12:12 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Criteris d&#8217;adjudicaci\u00f3<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=3\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Plec de cl\u00e0usules administratives particulars<\/span><\/a><\/td>\n<td class=\"centro\">14\/06\/2017 12:11 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Plec de cl\u00e0usules administratives particulars i Annexos<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=2\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Prescripcions t\u00e8cniques particulars <\/span><\/a><\/td>\n<td class=\"centro\">14\/06\/2017 12:08 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Plec prescripcions t\u00e8cniques particulars<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=27&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=7&amp;orden=1\" rel=\"external noopener\" target=\"_blank\"><span style=\"color: #333333;\">Anunci de licitaci\u00f3 <\/span><\/a><\/td>\n<td class=\"centro\">14\/06\/2017 12:08 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Anunci de licitaci\u00f3<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":295940,"parent":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-307749","licitaciones","type-licitaciones","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/licitaciones\/307749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/licitaciones"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/types\/licitaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media\/295940"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media?parent=307749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}