{"id":265051,"date":"2024-06-21T13:32:14","date_gmt":"2024-06-21T11:32:14","guid":{"rendered":"https:\/\/alicanteturismo.com\/?p=265051"},"modified":"2024-10-16T16:59:59","modified_gmt":"2024-10-16T14:59:59","slug":"doce-empresas-obtienen-el-distintivo-de-calidad-turistica-y-alicante-suma-ya-128-acreditaciones","status":"publish","type":"noticias","link":"https:\/\/dev.alicanteturismo.com\/ca\/noticias\/doce-empresas-obtienen-el-distintivo-de-calidad-turistica-y-alicante-suma-ya-128-acreditaciones\/","title":{"rendered":"Doce empresas obtienen el distintivo de calidad tur\u00edstica y Alicante suma ya 128 acreditaciones"},"content":{"rendered":"<p style=\"text-align: center;\">La <strong>obtenci\u00f3n del certificado Sicted<\/strong> implica la superaci\u00f3n de una auditor\u00eda que eval\u00faa aspectos como la atenci\u00f3n al cliente, la accesibilidad y la aplicaci\u00f3n de <strong>buenas pr\u00e1cticas tur\u00edsticas<\/strong><\/p>\n<p style=\"text-align: center;\">Poquet destaca \u201cel <strong>compromiso<\/strong> del sector tur\u00edstico por alcanzar la excelencia, lo que redunda en la oferta de calidad que queremos para nuestra ciudad\u201d<\/p>\n<p><strong>Alicante, 21 de junio de 2024. <\/strong>Un total de doce empresas <strong>han obtenido<\/strong> el certificado de calidad tur\u00edstica Sicted con lo que son ya <strong>128 las acreditaciones de excelencia<\/strong> que suma Alicante.<\/p>\n<p>La obtenci\u00f3n del certificado Sicted implica la <strong>superaci\u00f3n de una auditor\u00eda<\/strong> que eval\u00faa diferentes aspectos de la gesti\u00f3n empresarial, como<strong> la atenci\u00f3n al cliente, la accesibilidad o la aplicaci\u00f3n de buenas pr\u00e1cticas tur\u00edsticas.<\/strong> Los servicios tur\u00edsticos distinguidos se convierten en referentes de calidad ofreciendo a los visitantes una garant\u00eda de satisfacci\u00f3n y confianza.<\/p>\n<p>La concejala de Turismo, Ana Poquet, ha destacado \u201cel <strong>compromiso<\/strong> del sector tur\u00edstico por alcanzar <strong>la excelencia<\/strong>, lo que redunda en la oferta de calidad que queremos para nuestra ciudad\u201d.<\/p>\n<p>Las <strong>\u00faltimas empresas tur\u00edsticas en adherirse a Sicted<\/strong> son Casa Alberola Apartments, los restaurantes Abarrote, Chafl\u00e1n (Luceros y O\u2019 Donell), La Disfrutona, Miami y Palmitas, los gu\u00edas AlicanTours, Levante Guides y levanteguides.com, la agencia de viajes Blue Valley Travel y la empresa de experiencias Royaldelux.<\/p>\n<p>La <strong>adhesi\u00f3n a este certificado de calidad es voluntario<\/strong> y estas incorporaciones se producen tras la reciente celebraci\u00f3n de la Mesa de Calidad Sicted Alicante, presidida por la concejala de Turismo y la propuesta de los servicios tur\u00edsticos a distinguir, quienes superaron con \u00e9xito el Comit\u00e9 de Distinci\u00f3n.<\/p>\n<p><strong>Entre los servicios tur\u00edsticos propios de la ciudad<\/strong> que cuentan con este reconocimiento <strong>destacan<\/strong> las playas, el castillo de Santa B\u00e1rbara y las dos oficinas de turismo (Puerto y Renfe). Adem\u00e1s, cuentan con la distinci\u00f3n que acredita la calidad del servicio tur\u00edstico que prestan decenas de negocios de la ciudad como hoteles, restaurantes, apartamentos, comercios, empresas de transporte, de actividades deportivas, organizadores de eventos e incluso instituciones educativas.<\/p>\n<p><strong>Garant\u00eda de calidad<\/strong><\/p>\n<p>El fomento del Sicted por parte del Ayuntamiento de Alicante, a trav\u00e9s del Patronato de Turismo Alicante City&amp;Beach, <strong>se enmarca<\/strong> en la estrategia municipal de <strong>consolidar la ciudad como un destino tur\u00edstico de calidad.<\/strong> La adhesi\u00f3n de cada vez m\u00e1s servicios tur\u00edsticos al sistema contribuye a elevar el nivel general de la oferta tur\u00edstica y a f<strong>ortalecer la competitividad del destino<\/strong> en el mercado global.<\/p>\n<p>Sicted es un <strong>proyecto de mejora<\/strong> de la calidad de los destinos tur\u00edsticos promovido por la Secretar\u00eda de Estado de Turismo, con el apoyo de la Federaci\u00f3n Espa\u00f1ola de Municipios y Provincias (FEMP), que trabaja con servicios tur\u00edsticos de hasta 37 oficios diferentes con el <strong>objetivo de mejorar la experiencia y satisfacci\u00f3n del turista.<\/strong><\/p>\n<p>*<strong>En la imagen <\/strong>acto de reconocimiento a empresas que cumplen diez a\u00f1os en Sicted celebrado el pasado marzo.<\/p>\n","protected":false},"featured_media":266534,"template":"","meta":{"_acf_changed":false},"categoria-de-noticia":[153,160],"class_list":["post-265051","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categoria-de-noticia-notas-de-prensa","categoria-de-noticia-sicted"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/noticias\/265051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":0,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/noticias\/265051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media\/266534"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media?parent=265051"}],"wp:term":[{"taxonomy":"categoria-de-noticia","embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/categoria-de-noticia?post=265051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}