{"id":315503,"date":"2026-01-20T11:36:22","date_gmt":"2026-01-20T10:36:22","guid":{"rendered":"https:\/\/alicanteturismo.com\/?post_type=noticias&#038;p=315503"},"modified":"2026-01-22T12:56:36","modified_gmt":"2026-01-22T11:56:36","slug":"alicante-cierra-hasta-el-viernes-el-parking-del-paseo-de-gomiz-y-anuncia-cortes-de-trafico-por-obras-y-una-tractorada","status":"publish","type":"noticias","link":"https:\/\/dev.alicanteturismo.com\/ca\/noticias\/alicante-cierra-hasta-el-viernes-el-parking-del-paseo-de-gomiz-y-anuncia-cortes-de-trafico-por-obras-y-una-tractorada\/","title":{"rendered":"Alicante cierra hasta el viernes el parking del Paseo de G\u00f3miz y anuncia cortes de tr\u00e1fico por obras en Condes de Soto Ameno y una tractorada por el centro el jueves 29 de enero"},"content":{"rendered":"","protected":false},"featured_media":315513,"template":"","meta":{"_acf_changed":false},"categoria-de-noticia":[143,142,145],"class_list":["post-315503","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categoria-de-noticia-avisos-y-recomendaciones","categoria-de-noticia-informacion-practica","categoria-de-noticia-transporte-publico"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/noticias\/315503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":0,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/noticias\/315503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media\/315513"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/media?parent=315503"}],"wp:term":[{"taxonomy":"categoria-de-noticia","embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/ca\/wp-json\/wp\/v2\/categoria-de-noticia?post=315503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}