{"id":301223,"date":"2025-03-19T09:17:22","date_gmt":"2025-03-19T08:17:22","guid":{"rendered":"https:\/\/alicanteturismo.com\/?post_type=noticias&#038;p=301223"},"modified":"2025-04-03T17:20:40","modified_gmt":"2025-04-03T15:20:40","slug":"alicante-adelanta-a-san-jose-el-servicio-del-turibus-para-recorrer-lugares-singulares","status":"publish","type":"noticias","link":"https:\/\/dev.alicanteturismo.com\/de\/noticias\/alicante-adelanta-a-san-jose-el-servicio-del-turibus-para-recorrer-lugares-singulares\/","title":{"rendered":"Alicante adelanta a San Jos\u00e9 el servicio del Turib\u00fas para recorrer lugares singulares"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><strong>El autob\u00fas tur\u00edstico de la ciudad de Alicante fue utilizado por 31.125 pasajeros en 2024&nbsp;experimentando un crecimiento de un 5% en tan solo un a\u00f1o<\/strong><\/p>\n\n\n\n<p><strong>Alicante, 18 de marzo de\u00a02025<\/strong>.\u00a0Los <strong>turistas en Alicante <\/strong>est\u00e1n disfrutando cada vez m\u00e1s de sus vacaciones durante todo el a\u00f1o, y para poder atenderles mejor y hacer que su estancia sea m\u00e1s atractiva, el <strong>Ayuntamiento <\/strong>y Vectalia, empresa concesionaria del transporte urbano, adelantan al D\u00eda del Padre, festividad de San Jos\u00e9, la puesta en marcha del <strong>Turib\u00fas<\/strong>. Este servicio fue utilizado en 2024 por 31.125 de pasajeros, con un incremento del 5% en tan solo un a\u00f1o.<\/p>\n\n\n\n<p>Este servicio de autob\u00fas tiene su cabecera en la plaza <strong>Puerta del Mar <\/strong>con salidas a las horas en punto entre las 10 y las 13 y las 16 y 18 horas, con un recorrido circular de una hora con 11 paradas y que ofrece precios asequibles de 5, 10 y 7 euros para ni\u00f1os, adultos y tercera edad.<\/p>\n\n\n\n<p>El concejal de <strong>Movilidad <\/strong>Urbana, Carlos de Juan, ha resaltado \u201ceste a\u00f1o adelantamos la puesta en marcha de este servicio tur\u00edstico al festivo de San Jos\u00e9, D\u00eda del Padre, para atender la creciente demanda producida por el aumento de llega de turistas que eligen Alicante con destino para sus vacaciones\u201d. \u201cEl autob\u00fas fue renovado el a\u00f1o pasado con la adjudicaci\u00f3n del nuevo contrato ampliando el periodo de funcionamiento y mejorando el servicio con medios m\u00e1s modernos y ofreciendo una audiogu\u00eda en seis idiomas, que hacen de esta visita a la ciudad una opci\u00f3n muy atractiva\u201d, ha resaltado el edil.<\/p>\n\n\n\n<p>El <strong>veh\u00edculo <\/strong>dispone de <strong>70 plazas<\/strong>, distribuidas en doble altura y un servicio de traducci\u00f3n simult\u00e1nea en seis idiomas con auriculares y adem\u00e1s es accesible para personas con movilidad reducida.<\/p>\n\n\n\n<p>A partir del mi\u00e9rcoles 19 de marzo, el <strong>Turib\u00fas <\/strong>echar\u00e1 a <strong>rodar <\/strong>y ofrecer\u00e1 <strong>visitas guiadas <\/strong>a los <strong>turistas <\/strong>en seis idiomas: castellano, valenciano, ingl\u00e9s, franc\u00e9s, alem\u00e1n e italiano, en un recorrido de una hora para visitar los once lugares y monumentos singulares de la ciudad con la posibilidad de subir y bajar en cada parada del recorrido para visitar los monumentos o realizar compras durante todo el d\u00eda o realizar transbordos con otras l\u00edneas el <strong>autob\u00fas urbano<\/strong>.<\/p>\n\n\n\n<p>Cada a\u00f1o el n\u00famero de usuario de este servicio aumenta, si en 2023 fueron 29.713 las personas que se subieron a Turib\u00fas, el a\u00f1o pasado fueron 31.125, un 5% m\u00e1s en tan solo un a\u00f1o. El Turib\u00fas tiene su cabecera en la plaza Puerta del Mar (entre el puerto y la playa del Postiguet), con salidas cada hora en punto entre las 10 y las 13 y ls 16 y las 18 horas los siete d\u00edas de la semana. Realiza paradas cada cinco minutos, aproximadamente, en los principales atractivos tur\u00edsticos de Alicante: Castillo de Santa B\u00e1rbara (ascensor del Postiguet), Museo Arqueol\u00f3gico Provincial (MARQ) y enlace con la lanzadera de subida al castillo, Rambla (Comercio del Centro Tradicional, Casco Antiguo, Ayuntamiento, Concatedral de San Nicol\u00e1s, Bas\u00edlica de Santa Mar\u00eda,&#8230;), Plaza de Espa\u00f1a (Plaza de Toros, Museo Taurino, ADDA y Las Cigarreras), Mercado Central (Teatro Principal), plaza de los Luceros, Federico Soto y Maisonnave (zona comercial y de grandes almacenes), Estaci\u00f3n de Autobuses (Refugios antia\u00e9reos) y Puerto (Museo Ocean Race Village).<\/p>\n\n\n\n<p>Adem\u00e1s, mantiene correspondencia con las principales paradas del TRAM en el MARQ, Mercado Central y Luceros, as\u00ed como con las l\u00edneas del transporte urbano e interurbano.<\/p>\n\n\n\n<p>El turib\u00fas funciona desde el pasado a\u00f1o dentro de la concesi\u00f3n que el Ayuntamiento tiene con Vectalia MIA entre el 19 de marzo y el 8 de diciembre, con precios de 5 euros para ni\u00f1os, 10 para adultos y 7 para la tercera edad.<\/p>\n","protected":false},"featured_media":301224,"template":"","meta":{"_acf_changed":false},"categoria-de-noticia":[121,142,145],"class_list":["post-301223","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categoria-de-noticia-destacados","categoria-de-noticia-informacion-practica","categoria-de-noticia-transporte-publico"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/noticias\/301223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":0,"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/noticias\/301223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/media\/301224"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/media?parent=301223"}],"wp:term":[{"taxonomy":"categoria-de-noticia","embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/categoria-de-noticia?post=301223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}