{"id":315060,"date":"2025-12-19T11:51:12","date_gmt":"2025-12-19T10:51:12","guid":{"rendered":"https:\/\/alicanteturismo.com\/?post_type=noticias&#038;p=315060"},"modified":"2025-12-19T11:52:40","modified_gmt":"2025-12-19T10:52:40","slug":"alicante-pone-en-marcha-el-autobus-gratuito-para-recorrer-la-navidad-alicantina","status":"publish","type":"noticias","link":"https:\/\/dev.alicanteturismo.com\/de\/noticias\/alicante-pone-en-marcha-el-autobus-gratuito-para-recorrer-la-navidad-alicantina\/","title":{"rendered":"Alicante pone en marcha el autob\u00fas gratuito para recorrer la Navidad alicantina"},"content":{"rendered":"","protected":false},"featured_media":315063,"template":"","meta":{"_acf_changed":false},"categoria-de-noticia":[121,126,142,132,145],"class_list":["post-315060","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categoria-de-noticia-destacados","categoria-de-noticia-fiestas","categoria-de-noticia-informacion-practica","categoria-de-noticia-navidad","categoria-de-noticia-transporte-publico"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/noticias\/315060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":0,"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/noticias\/315060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/media\/315063"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/media?parent=315060"}],"wp:term":[{"taxonomy":"categoria-de-noticia","embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/de\/wp-json\/wp\/v2\/categoria-de-noticia?post=315060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}