{"id":304900,"date":"2018-03-03T11:51:00","date_gmt":"2018-03-03T10:51:00","guid":{"rendered":"https:\/\/alicanteturismo.com\/?post_type=licitaciones&#038;p=304900"},"modified":"2025-04-09T11:52:33","modified_gmt":"2025-04-09T09:52:33","slug":"el-servicio-de-asistencia-y-salvamento-en-las-playas-de-alicante-2","status":"publish","type":"licitaciones","link":"https:\/\/dev.alicanteturismo.com\/en\/licitaciones\/el-servicio-de-asistencia-y-salvamento-en-las-playas-de-alicante-2\/","title":{"rendered":"El servicio de asistencia y salvamento en las playas de Alicante"},"content":{"rendered":"<h3>Documentos Asociados<\/h3>\n<table summary=\"Documentos\" width=\"100%\">\n<colgroup>\n<col width=\"29%\" \/>\n<col width=\"21%\" \/>\n<col width=\"21%\" \/>\n<col width=\"29%\" \/><\/colgroup>\n<tbody>\n<tr class=\"par\">\n<th>Documento<\/th>\n<th class=\"centro\" abbr=\"Fecha\">Fecha Publicaci\u00f3n<\/th>\n<th class=\"centro\" abbr=\"Firma y sello de tiempo\">Verificaci\u00f3n Firma<\/th>\n<th>Observaciones<\/th>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=14\" rel=\"external noopener\" target=\"_blank\">Adjudicaci\u00f3n<\/a><\/td>\n<td class=\"centro\">02\/03\/2018 12:59 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Acuerdo adjudicaci\u00f3n Junta Rectora<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=13\" rel=\"external noopener\" target=\"_blank\">Clasificaci\u00f3n de los licitadores<\/a><\/td>\n<td class=\"centro\">13\/12\/2017 12:17 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Acuerdo clasificaci\u00f3n Junta Rectora<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=12\" rel=\"external noopener\" target=\"_blank\">Otros<\/a><\/td>\n<td class=\"centro\">13\/12\/2017 12:15 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Informe de valoraci\u00f3n proposiciones<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=11\" rel=\"external noopener\" target=\"_blank\">Otros<\/a><\/td>\n<td class=\"centro\">19\/10\/2017 09:28 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Fecha apertura sobre n\u00ba 2<\/p>\n<div>AVISO<\/div>\n<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=10\" rel=\"external noopener\" target=\"_blank\">Otros<\/a><\/td>\n<td class=\"centro\">16\/10\/2017 14:39 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">AVISO<\/p>\n<div>AVISO<\/div>\n<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=9\" rel=\"external noopener\" target=\"_blank\">Otros<\/a><\/td>\n<td class=\"centro\">29\/09\/2017 10:43 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">NOTA ACLARATORIA<\/p>\n<div>AVISO<\/div>\n<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=8\" rel=\"external noopener\" target=\"_blank\">Otros<\/a><\/td>\n<td class=\"centro\">18\/09\/2017 13:44 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Levantamiento suspensi\u00f3n y nuevos plazos<\/p>\n<div>AVISO<\/div>\n<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=7\" rel=\"external noopener\" target=\"_blank\">Otros<\/a><\/td>\n<td class=\"centro\">05\/06\/2017 10:52 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">AVISO SUSPENSI\u00d3N<\/p>\n<div>AVISO<\/div>\n<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=6\" rel=\"external noopener\" target=\"_blank\">Otros<\/a><\/td>\n<td class=\"centro\">24\/04\/2017 10:31 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Anexos al pliego de cl\u00e1usulas administrativas particulares<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=5\" rel=\"external noopener\" target=\"_blank\">Pliego de cl\u00e1usulas administrativas particulares<\/a><\/td>\n<td class=\"centro\">24\/04\/2017 10:28 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Pliego de cl\u00e1usulas administrativas particulares<\/td>\n<\/tr>\n<tr class=\"tr_impar impar\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=4\" rel=\"external noopener\" target=\"_blank\">Prescripciones t\u00e9cnicas particulares<\/a><\/td>\n<td class=\"centro\">24\/04\/2017 10:26 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<td class=\"izquierda\">Pliego de prescripciones t\u00e9cnicas particulares<\/td>\n<\/tr>\n<tr class=\"par\">\n<td class=\"izquierda\"><a class=\"pdf\" href=\"https:\/\/sedeelectronica.alicante.es\/blob_documento.php?expe=14&amp;ano_expe=17&amp;depto=PMT&amp;dep_expe=4&amp;orden=1\" rel=\"external noopener\" target=\"_blank\">Anuncio de licitaci\u00f3n<\/a><\/td>\n<td class=\"centro\">21\/04\/2017 14:54 h.<\/td>\n<td class=\"centro\">&#8211;<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":204745,"parent":0,"template":"","meta":{"_acf_changed":false},"class_list":["post-304900","licitaciones","type-licitaciones","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/en\/wp-json\/wp\/v2\/licitaciones\/304900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/en\/wp-json\/wp\/v2\/licitaciones"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/en\/wp-json\/wp\/v2\/types\/licitaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/en\/wp-json\/wp\/v2\/media\/204745"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/en\/wp-json\/wp\/v2\/media?parent=304900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}