{"id":264554,"date":"2024-06-03T10:03:14","date_gmt":"2024-06-03T08:03:14","guid":{"rendered":"https:\/\/alicanteturismo.com\/?p=264554"},"modified":"2024-10-16T17:01:19","modified_gmt":"2024-10-16T15:01:19","slug":"las-playas-de-san-juan-y-muchavista-acogen-torneos-masculino-y-femenino-del-mejor-voley-de-europa","status":"publish","type":"noticias","link":"https:\/\/dev.alicanteturismo.com\/fr\/noticias\/las-playas-de-san-juan-y-muchavista-acogen-torneos-masculino-y-femenino-del-mejor-voley-de-europa\/","title":{"rendered":"Las playas de San Juan y Muchavista acogen torneos masculino y femenino del mejor voley de Europa"},"content":{"rendered":"<p style=\"text-align: center;\">El edill Toni Gallego <strong>subraya<\/strong> que \u00ab\u00a0estas playas son un <strong>excelente reclamo tur\u00edstico<\/strong> y est\u00e1n perfectamente preparadas para acontecimientos deportivos de nivel\u00a0\u00bb<\/p>\n<p style=\"text-align: left;\"><strong>Las playas de San Juan y Muchavista han acogido este pasado fin de semana sendos torneos masculino y femenino de voley-playa en el que han participado las mejores parejas masculinas y femeninas de Europa. El concejal de Deportes, Toni Gallego, que ha presenciado las finales y entregado las medallas a las parejas ganadoras ha subrayado que \u00ab\u00a0estas playas son un excelente reclamo tur\u00edstico y, adem\u00e1s, est\u00e1n perfectamente preparadas para albergar acontecimientos deportivos de primer nivel.\u00a0<\/strong><\/p>\n<p style=\"text-align: left;\">La disputa de este doble torneo ha supuesto el colof\u00f3n, aun sin figurar en su programaci\u00f3n, de los Costa Blanca Beach Games que se desarrollaron durante los dos \u00faltimos fines de semana, \u00ab\u00a0lo que pone de relieve la <strong>capacidad de organizaci\u00f3n y las posibilidades<\/strong> que tiene la playa de San Juan para el turismo deportivo\u00a0\u00bb, ha sostenido Gallego. Las rondas previas del WEVZA femenino, puntuable para el ranking internacional, se desarrollaron durante la semana la final se celebr\u00f3 el s\u00e1bado. La final masculina se disput\u00f3 este domingo.<\/p>\n","protected":false},"featured_media":266516,"template":"","meta":{"_acf_changed":false},"categoria-de-noticia":[153],"class_list":["post-264554","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categoria-de-noticia-notas-de-prensa"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/noticias\/264554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":0,"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/noticias\/264554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/media\/266516"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/media?parent=264554"}],"wp:term":[{"taxonomy":"categoria-de-noticia","embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/categoria-de-noticia?post=264554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}