{"id":310322,"date":"2025-08-04T12:21:50","date_gmt":"2025-08-04T10:21:50","guid":{"rendered":"https:\/\/alicanteturismo.com\/?post_type=noticias&#038;p=310322"},"modified":"2025-09-02T13:39:02","modified_gmt":"2025-09-02T11:39:02","slug":"alicante-acoge-el-partido-espana-suiza-clasificatorio-para-el-eurovolley-de-2026","status":"publish","type":"noticias","link":"https:\/\/dev.alicanteturismo.com\/fr\/noticias\/alicante-acoge-el-partido-espana-suiza-clasificatorio-para-el-eurovolley-de-2026\/","title":{"rendered":"Alicante acoge el partido Espa\u00f1a &#8211; Suiza clasificatorio para el Eurovolley de 2026"},"content":{"rendered":"\n<p>El partido de la selecci\u00f3n masculina se disputar\u00e1 en el Pabell\u00f3n Pedro Ferr\u00e1ndiz, el 13 de agosto a las 19.30 horas, y las entradas se pueden adquirir en la web de la Federaci\u00f3n con descuentos del 50%.<\/p>\n\n\n\n<p>La emoci\u00f3n del voleibol europeo vuelve de nuevo a Alicante. El pr\u00f3ximo 13 de agosto, a las 19.30 horas, la selecci\u00f3n masculina absoluta espa\u00f1ola, conocida como los RedLynxes, se enfrentar\u00e1 a Suiza en el Pabell\u00f3n Pedro Ferr\u00e1ndiz, en un encuentro clave de la fase clasificatoria de cara al EuroVolley de 2026.<\/p>\n\n\n\n<p>La fase de clasificaci\u00f3n para el Campeonato de Europa del pr\u00f3ximo a\u00f1o afronta su recta final y la selecci\u00f3n masculina de voleibol necesita reaccionar para conseguir un billete directo al torneo. Despu\u00e9s de caer en la primera ronda ante Suiza y Suecia, los RedLynxex encaran la segunda ronda con un primer partido el 9 de agosto en Habo (Suecia) y el \u00faltimo cuatro d\u00edas despu\u00e9s en Alicante frente a la selecci\u00f3n helv\u00e9tica.<\/p>\n\n\n\n<p>El partido lo organiza la Federaci\u00f3n Espa\u00f1ola de Voleibol y las entradas se pueden adquirir en su p\u00e1gina web (rfevb.com) a un precio de 10 euros con un descuento del 50% hasta el 1 de agosto.<\/p>\n\n\n\n<p>La selecci\u00f3n nacional masculina que dirige Hubert Henno ya prepara desde el mes de julio en Guadalajara estos dos compromisos oficiales en Suecia y Alicante con el objetivo de estar presentes en la nueva edici\u00f3n del EuroVolley del a\u00f1o pr\u00f3ximo.<\/p>\n\n\n\n<p>Gran ambiente con Las Leonas del V\u00f3ley<\/p>\n\n\n\n<p>La \u00e9lite del voleibol continental por selecciones ya se dio cita en Alicante el primer fin de semana el pasado mes de junio con sendos partidos de la selecci\u00f3n espa\u00f1ola femenina, correspondientes a la European Golden League, frente a Croacia y Suecia. Las Leonas del V\u00f3ley congregaron a 3.000 y 4.500 espectadores, respectivamente, el 6 y 8 de junio en el pabell\u00f3n Pedro Ferr\u00e1ndiz, el mismo escenario para el choque de los RedLynxes del pr\u00f3ximo 13 de agosto<\/p>\n\n\n\n<p><\/p>\n","protected":false},"featured_media":310323,"template":"","meta":{"_acf_changed":false},"categoria-de-noticia":[119,121],"class_list":["post-310322","noticias","type-noticias","status-publish","has-post-thumbnail","hentry","categoria-de-noticia-deportes","categoria-de-noticia-destacados"],"acf":[],"_links":{"self":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/noticias\/310322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/types\/noticias"}],"version-history":[{"count":0,"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/noticias\/310322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/media\/310323"}],"wp:attachment":[{"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/media?parent=310322"}],"wp:term":[{"taxonomy":"categoria-de-noticia","embeddable":true,"href":"https:\/\/dev.alicanteturismo.com\/fr\/wp-json\/wp\/v2\/categoria-de-noticia?post=310322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}